{"id":124,"date":"2010-09-02T12:11:07","date_gmt":"2010-09-02T15:11:07","guid":{"rendered":"http:\/\/www.thiagosantos.com\/blog\/?p=124"},"modified":"2010-09-08T13:45:48","modified_gmt":"2010-09-08T16:45:48","slug":"cookie-para-que-nao-se-repita-mais","status":"publish","type":"post","link":"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/","title":{"rendered":"Cookie, para que n\u00e3o se repita mais."},"content":{"rendered":"<p>Aprender com o tempo, \u00e9 uma metaf\u00f3ra n\u00e3o se esque\u00e7a disso. Ninguem aprende com o tempo, nem o tempo aprende conosco. O tempo passa e se n\u00f3s n\u00e3o estivemos na roda ele vai girar\u00a0 perdemos a vez e o conhecimento se n\u00e3o treinarmos e nem estudarmos.<br \/>\nAprender com o tempo \u00e9: voc\u00ea que est\u00e1 na roda, girando igual a todo mundo, mantendo atividades a qual seja necess\u00e1rio usar a mente de forma a resolver quebra-cabe\u00e7as, aprendendo com os movimento, acertando e errando.<\/p>\n<p>Pois bem, creio que o <span style=\"color: #333399;\">setcookie <\/span>seja uma fun\u00e7\u00e3o t\u00edpica e comum de usu\u00e1rio do PHP. Usando essa fun\u00e7\u00e3o que perdi, por distra\u00e7\u00e3o, dois dias de trabalho o que acho ser um absurdo. Abaixo segue um cen\u00e1rio a qual eu me encontrava e a solu\u00e7\u00e3o encontrada.<\/p>\n<p><!--more--><\/p>\n<p>Vou dar uma passada no <span style=\"color: #333399;\">setcookie<\/span>:<\/p>\n<address><span style=\"color: #333399;\"><span style=\"color: #000000;\">setcookie<\/span>(_nome [, _valor , _data_expiracao , _path , _domain, _secure, _httponly ])<\/span><\/address>\n<p>Exceto o _nome, todos os outros campos s\u00e3o opcionais.<\/p>\n<p><strong>_nome<\/strong> &#8211; nome do cookie<br \/>\n<strong>_valor<\/strong> &#8211; valor que o cookie vai ter, se nada for definido ele ser\u00e1 string vazia ( &#8220;&#8221; )<br \/>\n<strong>_data_expiracao<\/strong> &#8211; data em que o cookie vai expirar<br \/>\n<strong>_path<\/strong> &#8211; local onde o cookie vai estar disponivel [ rs ]<br \/>\n<strong>_domain<\/strong> &#8211; dominio onde o cookie vai estar disponivel ( .thiagosantos.com [ todo os subdominios ], www.thiagosantos.com [ somente no www ] ), se o domain n\u00e3o for definido vai ser utilizado o dominio que fez a requisicao do cookie.<br \/>\n<strong>_secure<\/strong> &#8211; true ou false, o cookie s\u00f3 sera transmitido via HTTPS<br \/>\n<strong>_httponly<\/strong> &#8211; muito bacana, o cookie fica &#8220;invisivel&#8221; para o javasxcript a partir do PHP 5.2<\/p>\n<p>Cen\u00e1rio, a partir da <em><strong>&#8216;\/&#8217;<\/strong><\/em> eu fazia uma requisicao por ajax para o caminho <strong><em>&#8216;\/buu\/foo&#8217;<\/em><\/strong> que fazia o que tinha de ser feito e depois setava um cookie. Quando eu atualizava a p\u00e1gina a informa\u00e7\u00e3o que deveria aparecer na p\u00e1gina inicial, simplesmente n\u00e3o aparecia. Dai achei que era algum problema comigo, e implementei um retorno que definia o cookie pelo javascript localizado no<em><strong> &#8216;\/&#8217;<\/strong><\/em>.<br \/>\nEnt\u00e3o eu tinha dois pontos que setavam o mesmo cookie um pelo PHP e o outro pelo Javascript. E quando eu tentava apagar o cookie pelo javascript a informa\u00e7\u00e3o simplesmente sumia, como esperado. Mas quando fazia uma nova requisicao por ajax ao<strong><em> &#8216;\/buu\/foo<\/em><\/strong>&#8216; todas as informa\u00e7\u00f5es do cookie antigo que haviam sido apagadas pelo Javascript simplesmente voltavam!!<br \/>\nOoohhh!!!<br \/>\nJ\u00e1 deu pra entender o que eu tinha esquisito quando defini o cookie no PHP n\u00e9?<br \/>\n\u00c9eeehh isso mesmo esqueci de definir o &#8216;path&#8217; no <span style=\"color: #333399;\">setcookie<\/span>, quando eu apagava o cookie pelo Javascript, eu apagava o mesmo que eu tinha definido antes s\u00f3 que para<strong><em> &#8216;\/&#8217; <\/em><\/strong>, mas n\u00e3o apagava o que eu havia setado para o PHP em <em><strong>&#8216;\/buu\/foo&#8217;<\/strong><\/em> &#8230; rs<br \/>\nEnt\u00e3o \u00e9 isso, defini o path no PHP para <em><strong>&#8216;\/&#8217;<\/strong><\/em> e removi a implementa\u00e7\u00e3o de cookie por Javascript, umas vez que n\u00e3o se vazia mais necess\u00e1rio.<br \/>\nE tudo m\u00e1gicamente come\u00e7ou a funcionar como o esperado.<\/p>\n<p>Mas uma gota de experi\u00eancia deixada no blog.<\/p>\n<p>At\u00e9 mais,<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprender com o tempo, \u00e9 uma metaf\u00f3ra n\u00e3o se esque\u00e7a disso. Ninguem aprende com o tempo, nem o tempo aprende conosco. O tempo passa e se n\u00f3s n\u00e3o estivemos na roda ele vai girar\u00a0 perdemos a vez e o conhecimento se n\u00e3o treinarmos e nem estudarmos. Aprender com o tempo \u00e9: voc\u00ea que est\u00e1 na [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[50,171,170,49],"class_list":["post-124","post","type-post","status-publish","format-standard","hentry","category-javascript","category-php","tag-cookie","tag-javascript","tag-php","tag-setcookie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cookie, para que n\u00e3o se repita mais. - Pereira, Thiago Santos.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie, para que n\u00e3o se repita mais. - Pereira, Thiago Santos.\" \/>\n<meta property=\"og:description\" content=\"Aprender com o tempo, \u00e9 uma metaf\u00f3ra n\u00e3o se esque\u00e7a disso. Ninguem aprende com o tempo, nem o tempo aprende conosco. O tempo passa e se n\u00f3s n\u00e3o estivemos na roda ele vai girar\u00a0 perdemos a vez e o conhecimento se n\u00e3o treinarmos e nem estudarmos. Aprender com o tempo \u00e9: voc\u00ea que est\u00e1 na [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/\" \/>\n<meta property=\"og:site_name\" content=\"Pereira, Thiago Santos.\" \/>\n<meta property=\"article:published_time\" content=\"2010-09-02T15:11:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-09-08T16:45:48+00:00\" \/>\n<meta name=\"author\" content=\"Pereira, Thiago Santos\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pereira, Thiago Santos\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/\",\"url\":\"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/\",\"name\":\"Cookie, para que n\u00e3o se repita mais. - Pereira, Thiago Santos.\",\"isPartOf\":{\"@id\":\"https:\/\/thiagosantos.com\/blog\/#website\"},\"datePublished\":\"2010-09-02T15:11:07+00:00\",\"dateModified\":\"2010-09-08T16:45:48+00:00\",\"author\":{\"@id\":\"https:\/\/thiagosantos.com\/blog\/#\/schema\/person\/56683334c52027e200fd9270c17c629d\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/thiagosantos.com\/blog\/#website\",\"url\":\"https:\/\/thiagosantos.com\/blog\/\",\"name\":\"Pereira, Thiago Santos.\",\"description\":\"the fun of code.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/thiagosantos.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/thiagosantos.com\/blog\/#\/schema\/person\/56683334c52027e200fd9270c17c629d\",\"name\":\"Pereira, Thiago Santos\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/thiagosantos.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ed936469f86e5f07085e7540b2c0a115?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ed936469f86e5f07085e7540b2c0a115?s=96&d=mm&r=g\",\"caption\":\"Pereira, Thiago Santos\"},\"description\":\"Um cara que mora no Rio e n\u00e3o sabe nadar.\",\"sameAs\":[\"http:\/\/thiagosantos.com\"],\"url\":\"https:\/\/thiagosantos.com\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie, para que n\u00e3o se repita mais. - Pereira, Thiago Santos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/","og_locale":"pt_BR","og_type":"article","og_title":"Cookie, para que n\u00e3o se repita mais. - Pereira, Thiago Santos.","og_description":"Aprender com o tempo, \u00e9 uma metaf\u00f3ra n\u00e3o se esque\u00e7a disso. Ninguem aprende com o tempo, nem o tempo aprende conosco. O tempo passa e se n\u00f3s n\u00e3o estivemos na roda ele vai girar\u00a0 perdemos a vez e o conhecimento se n\u00e3o treinarmos e nem estudarmos. Aprender com o tempo \u00e9: voc\u00ea que est\u00e1 na [&hellip;]","og_url":"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/","og_site_name":"Pereira, Thiago Santos.","article_published_time":"2010-09-02T15:11:07+00:00","article_modified_time":"2010-09-08T16:45:48+00:00","author":"Pereira, Thiago Santos","twitter_misc":{"Escrito por":"Pereira, Thiago Santos","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/","url":"https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/","name":"Cookie, para que n\u00e3o se repita mais. - Pereira, Thiago Santos.","isPartOf":{"@id":"https:\/\/thiagosantos.com\/blog\/#website"},"datePublished":"2010-09-02T15:11:07+00:00","dateModified":"2010-09-08T16:45:48+00:00","author":{"@id":"https:\/\/thiagosantos.com\/blog\/#\/schema\/person\/56683334c52027e200fd9270c17c629d"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/thiagosantos.com\/blog\/124\/php\/cookie-para-que-nao-se-repita-mais\/"]}]},{"@type":"WebSite","@id":"https:\/\/thiagosantos.com\/blog\/#website","url":"https:\/\/thiagosantos.com\/blog\/","name":"Pereira, Thiago Santos.","description":"the fun of code.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thiagosantos.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/thiagosantos.com\/blog\/#\/schema\/person\/56683334c52027e200fd9270c17c629d","name":"Pereira, Thiago Santos","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/thiagosantos.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ed936469f86e5f07085e7540b2c0a115?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ed936469f86e5f07085e7540b2c0a115?s=96&d=mm&r=g","caption":"Pereira, Thiago Santos"},"description":"Um cara que mora no Rio e n\u00e3o sabe nadar.","sameAs":["http:\/\/thiagosantos.com"],"url":"https:\/\/thiagosantos.com\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/posts\/124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/comments?post=124"}],"version-history":[{"count":7,"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/posts\/124\/revisions"}],"predecessor-version":[{"id":142,"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/posts\/124\/revisions\/142"}],"wp:attachment":[{"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/media?parent=124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/categories?post=124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/thiagosantos.com\/blog\/wp-json\/wp\/v2\/tags?post=124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}